{"id":5347,"date":"2020-10-06T13:57:49","date_gmt":"2020-10-06T13:57:49","guid":{"rendered":"https:\/\/www.ppeng.ch\/erneuerung-des-soldini-viertels-chiasso-schweiz\/"},"modified":"2020-10-06T13:59:07","modified_gmt":"2020-10-06T13:59:07","slug":"erneuerung-des-soldini-viertels-chiasso-schweiz","status":"publish","type":"post","link":"https:\/\/www.ppeng.ch\/de\/erneuerung-des-soldini-viertels-chiasso-schweiz\/","title":{"rendered":"Erneuerung des Soldini-Viertels, CHIASSO &#8211; SCHWEIZ"},"content":{"rendered":"\n<p>Das Projekt betrifft die Neugestaltung des \u00f6ffentlichen Raums im Soldini-Viertel von Chiasso, in welchem 2\u2019300 Menschen leben und verschiedene handwerkliche und industrielle Produktionst\u00e4tigkeiten stattfinden. Die Ziele des Projekts sind die Reorganisation des Strassensystems, die Verwendung von wertvollen Materialien f\u00fcr die Pfl\u00e4sterung und die Ausstattung mit visuellen Elementen zur Verkehrsberuhigung der Strassen, die Schaffung von Verbindungsr\u00e4umen zwischen Bereichen mit privater und\/oder \u00f6ffentlichen Nutzung, die F\u00f6rderung der Langsamverkehrs mit der Schaffung und Anpassung von Radund Gehwegen, die Verbesserung der Sicherheit, die Beschr\u00e4nkung des Zugangs zu den bestehenden privaten Liegenschaften auf die Bewohner. \r\nDas Projekt umfasst die Sanierung und Anpassung der \u00f6ffentlichen Strassen, die Schaffung und Abgrenzung von R\u00e4umen f\u00fcr den Langsamverkehr, die Neugestaltung des \u00f6ffentlichen Raums des Quartiers, einschliesslich der Anpassung der gesamten unterirdischen Infrastruktur, der Stadtm\u00f6blierung und der -Beleuchtung. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt betrifft die Neugestaltung des \u00f6ffentlichen Raums im Soldini-Viertel von Chiasso, in welchem 2\u2019300 Menschen leben und verschiedene handwerkliche und industrielle Produktionst\u00e4tigkeiten stattfinden. Die Ziele des Projekts sind die Reorganisation des Strassensystems, die Verwendung von wertvollen Materialien f\u00fcr die Pfl\u00e4sterung und die Ausstattung mit visuellen Elementen zur Verkehrsberuhigung der Strassen, die Schaffung von Verbindungsr\u00e4umen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5347"}],"collection":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/comments?post=5347"}],"version-history":[{"count":3,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5347\/revisions"}],"predecessor-version":[{"id":5362,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5347\/revisions\/5362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media\/5335"}],"wp:attachment":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media?parent=5347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/categories?post=5347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/tags?post=5347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}