{"id":5636,"date":"2020-10-12T08:13:40","date_gmt":"2020-10-12T08:13:40","guid":{"rendered":"https:\/\/www.ppeng.ch\/n2-tunnelinspektionen-schweizerhalle-und-arisdorf-schweiz\/"},"modified":"2020-10-12T08:14:52","modified_gmt":"2020-10-12T08:14:52","slug":"n2-tunnelinspektionen-schweizerhalle-und-arisdorf-schweiz","status":"publish","type":"post","link":"https:\/\/www.ppeng.ch\/de\/n2-tunnelinspektionen-schweizerhalle-und-arisdorf-schweiz\/","title":{"rendered":"N2, Tunnelinspektionen Schweizerhalle und Arisdorf &#8211; SCHWEIZ"},"content":{"rendered":"\n<p>Das Projekt umfasst Inspektionen in den Jahren 2013, 2018 und 2023 f\u00fcr den Schweizerhallentunnel und den Arisdorftunnel mit L\u00e4ngen von 1\u2019030 m bzw. 1\u2019349 m.\r\nNach einer ersten KUBA-Ausbildungsphase erfolgt die Identifikation und Datenerhebung der Strukturen, anschliessend deren Hauptuntersuchung (Kontrolle, Analyse und Bewertung des einzelnen Strukturelements) und schliesslich die Schlussdokumentation mit dem vorgeschlagenen Interventionskonzept.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt umfasst Inspektionen in den Jahren 2013, 2018 und 2023 f\u00fcr den Schweizerhallentunnel und den Arisdorftunnel mit L\u00e4ngen von 1\u2019030 m bzw. 1\u2019349 m. Nach einer ersten KUBA-Ausbildungsphase erfolgt die Identifikation und Datenerhebung der Strukturen, anschliessend deren Hauptuntersuchung (Kontrolle, Analyse und Bewertung des einzelnen Strukturelements) und schliesslich die Schlussdokumentation mit dem vorgeschlagenen Interventionskonzept.<\/p>\n","protected":false},"author":1,"featured_media":5625,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5636"}],"collection":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/comments?post=5636"}],"version-history":[{"count":3,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5636\/revisions"}],"predecessor-version":[{"id":5651,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5636\/revisions\/5651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media\/5625"}],"wp:attachment":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media?parent=5636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/categories?post=5636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/tags?post=5636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}