{"id":5948,"date":"2020-10-02T14:55:33","date_gmt":"2020-10-02T14:55:33","guid":{"rendered":"https:\/\/www.ppeng.ch\/atg-l609-deponieaushubmateriel-buzza-biasca-schweiz\/"},"modified":"2020-11-19T12:44:51","modified_gmt":"2020-11-19T12:44:51","slug":"atg-l609-deponieaushubmateriel-buzza-biasca-schweiz","status":"publish","type":"post","link":"https:\/\/www.ppeng.ch\/de\/atg-l609-deponieaushubmateriel-buzza-biasca-schweiz\/","title":{"rendered":"ATG &#8211; L609 Deponieaushubmaterial Buzza, BIASCA &#8211; SCHWEIZ"},"content":{"rendered":"\n<p>Das Projekt betrifft eines der Lose, die die neue ATG-Eisenbahnlinie im Abschnitt Biasca betreffen. Das Projekt betrifft den Bau der Endlagerung des Materials, das aus dem Ausbruch des Gotthard-Basistunnels stammt und im Rahmen des Projekts nicht wiederverwendet wird. Der Transport erfolgte mittels F\u00f6rderb\u00e4nder durch den Tunnel Pollegio Nord &#8211; Buzza di Biasca, der einen k\u00fcnstlichen H\u00fcgel an einem Ort bildet, der bereits historisch von einem Erdrutsch betroffen war (im Jahr 1513) und sp\u00e4ter als Steinbruch f\u00fcr Zuschlagstoffe ausgebeutet wurde. Die Arbeiten zur Kompensation und Umweltverbesserung wurden in Etappen durchgef\u00fchrt, wodurch die Subtraktion landwirtschaftlicher Nutzfl\u00e4chen im Voraus wieder ausgeglichen wurde. Die Lagerst\u00e4tte hat eine Kapazit\u00e4t von etwa 4,2 Millionen m\u00b3 und umfasst eine Fl\u00e4che von 140.000 m\u00b2. Dank der Landschaftsgestaltung sieht der Buzza nun wie ein in der Wachstumsphase gepflanzter H\u00fcgel aus und ist daher gr\u00fcn. Die Plantagen respektieren die einheimischen Arten mit Kastanien-, Eichen- und Flaumeichen, Eichen und semi-xerischen Str\u00e4uchern. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt betrifft eines der Lose, die die neue ATG-Eisenbahnlinie im Abschnitt Biasca betreffen. Das Projekt betrifft den Bau der Endlagerung des Materials, das aus dem Ausbruch des Gotthard-Basistunnels stammt und im Rahmen des Projekts nicht wiederverwendet wird. Der Transport erfolgte mittels F\u00f6rderb\u00e4nder durch den Tunnel Pollegio Nord &#8211; Buzza di Biasca, der einen k\u00fcnstlichen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5125,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5948"}],"collection":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/comments?post=5948"}],"version-history":[{"count":5,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5948\/revisions"}],"predecessor-version":[{"id":6968,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/posts\/5948\/revisions\/6968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media\/5125"}],"wp:attachment":[{"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/media?parent=5948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/categories?post=5948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ppeng.ch\/de\/wp-json\/wp\/v2\/tags?post=5948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}